{"id":2894,"date":"2026-09-02T01:15:28","date_gmt":"2026-09-01T23:15:28","guid":{"rendered":"http:\/\/public-heroes.npm13.net\/maximilian-408-348\/"},"modified":"2026-09-02T01:15:28","modified_gmt":"2026-09-01T23:15:28","slug":"maximilian-408-348","status":"publish","type":"post","link":"https:\/\/www.public-heroes.de\/de\/maximilian-408-348\/","title":{"rendered":"maximilian 408-348"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":111476,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[11],"tags":[17,14],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>maximilian 408-348 - people agentur - model - actor - artist - berlin<\/title>\n<meta name=\"description\" content=\"people casting agentur berlin, germany - model - actor - artist -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.public-heroes.de\/de\/maximilian-408-348\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"maximilian 408-348 - people agentur - model - actor - artist - berlin\" \/>\n<meta property=\"og:description\" content=\"people casting agentur berlin, germany - model - actor - artist -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.public-heroes.de\/de\/maximilian-408-348\/\" \/>\n<meta property=\"og:site_name\" content=\"public-heroes.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/publicheroesgmbh\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-01T23:15:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.public-heroes.de\/wp-content\/uploads\/2020\/01\/maximilian_408-348.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"570\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.public-heroes.de\/#website\",\"url\":\"https:\/\/www.public-heroes.de\/\",\"name\":\"public-heroes.de\",\"description\":\"people- &amp; castingagentur berlin\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.public-heroes.de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.public-heroes.de\/de\/maximilian-408-348\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"https:\/\/www.public-heroes.de\/wp-content\/uploads\/2020\/01\/maximilian_408-348.jpg\",\"contentUrl\":\"https:\/\/www.public-heroes.de\/wp-content\/uploads\/2020\/01\/maximilian_408-348.jpg\",\"width\":540,\"height\":570,\"caption\":\"408-348 | People | ab berlin\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.public-heroes.de\/de\/maximilian-408-348\/#webpage\",\"url\":\"https:\/\/www.public-heroes.de\/de\/maximilian-408-348\/\",\"name\":\"maximilian 408-348 - people agentur - model - actor - artist - berlin\",\"isPartOf\":{\"@id\":\"https:\/\/www.public-heroes.de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.public-heroes.de\/de\/maximilian-408-348\/#primaryimage\"},\"datePublished\":\"2026-09-01T23:15:28+00:00\",\"dateModified\":\"2026-09-01T23:15:28+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"people casting agentur berlin, germany - model - actor - artist -\",\"breadcrumb\":{\"@id\":\"https:\/\/www.public-heroes.de\/de\/maximilian-408-348\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.public-heroes.de\/de\/maximilian-408-348\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.public-heroes.de\/de\/maximilian-408-348\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.public-heroes.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"maximilian 408-348\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"maximilian 408-348 - people agentur - model - actor - artist - berlin","description":"people casting agentur berlin, germany - model - actor - artist -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.public-heroes.de\/de\/maximilian-408-348\/","og_locale":"de_DE","og_type":"article","og_title":"maximilian 408-348 - people agentur - model - actor - artist - berlin","og_description":"people casting agentur berlin, germany - model - actor - artist -","og_url":"https:\/\/www.public-heroes.de\/de\/maximilian-408-348\/","og_site_name":"public-heroes.de","article_publisher":"https:\/\/www.facebook.com\/publicheroesgmbh","article_published_time":"2026-09-01T23:15:28+00:00","og_image":[{"width":540,"height":570,"url":"https:\/\/www.public-heroes.de\/wp-content\/uploads\/2020\/01\/maximilian_408-348.jpg","type":"image\/jpeg"}],"twitter_card":"summary","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.public-heroes.de\/#website","url":"https:\/\/www.public-heroes.de\/","name":"public-heroes.de","description":"people- &amp; castingagentur berlin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.public-heroes.de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","@id":"https:\/\/www.public-heroes.de\/de\/maximilian-408-348\/#primaryimage","inLanguage":"de","url":"https:\/\/www.public-heroes.de\/wp-content\/uploads\/2020\/01\/maximilian_408-348.jpg","contentUrl":"https:\/\/www.public-heroes.de\/wp-content\/uploads\/2020\/01\/maximilian_408-348.jpg","width":540,"height":570,"caption":"408-348 | People | ab berlin"},{"@type":"WebPage","@id":"https:\/\/www.public-heroes.de\/de\/maximilian-408-348\/#webpage","url":"https:\/\/www.public-heroes.de\/de\/maximilian-408-348\/","name":"maximilian 408-348 - people agentur - model - actor - artist - berlin","isPartOf":{"@id":"https:\/\/www.public-heroes.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.public-heroes.de\/de\/maximilian-408-348\/#primaryimage"},"datePublished":"2026-09-01T23:15:28+00:00","dateModified":"2026-09-01T23:15:28+00:00","author":{"@id":""},"description":"people casting agentur berlin, germany - model - actor - artist -","breadcrumb":{"@id":"https:\/\/www.public-heroes.de\/de\/maximilian-408-348\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.public-heroes.de\/de\/maximilian-408-348\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.public-heroes.de\/de\/maximilian-408-348\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.public-heroes.de\/"},{"@type":"ListItem","position":2,"name":"maximilian 408-348"}]}]}},"_links":{"self":[{"href":"https:\/\/www.public-heroes.de\/de\/wp-json\/wp\/v2\/posts\/2894"}],"collection":[{"href":"https:\/\/www.public-heroes.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.public-heroes.de\/de\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/www.public-heroes.de\/de\/wp-json\/wp\/v2\/comments?post=2894"}],"version-history":[{"count":1,"href":"https:\/\/www.public-heroes.de\/de\/wp-json\/wp\/v2\/posts\/2894\/revisions"}],"predecessor-version":[{"id":14963,"href":"https:\/\/www.public-heroes.de\/de\/wp-json\/wp\/v2\/posts\/2894\/revisions\/14963"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.public-heroes.de\/de\/wp-json\/wp\/v2\/media\/111476"}],"wp:attachment":[{"href":"https:\/\/www.public-heroes.de\/de\/wp-json\/wp\/v2\/media?parent=2894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.public-heroes.de\/de\/wp-json\/wp\/v2\/categories?post=2894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.public-heroes.de\/de\/wp-json\/wp\/v2\/tags?post=2894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}